{"id":18565,"date":"2021-10-11T11:36:00","date_gmt":"2021-10-11T09:36:00","guid":{"rendered":"https:\/\/swipcar.wpengine.com\/?p=18565"},"modified":"2021-10-06T11:37:26","modified_gmt":"2021-10-06T09:37:26","slug":"wltp","status":"publish","type":"post","link":"https:\/\/swipcar.com\/es\/blog\/wltp","title":{"rendered":"WLTP, \u00bfqu\u00e9 es?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/swipcar.com\/es\/blog\/wltp\/#%c2%bfque-significa-wltp\" >\u00bfQu\u00e9 significa WLTP?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/swipcar.com\/es\/blog\/wltp\/#%c2%bfcuando-entro-en-vigor-el-wltp\" >\u00bfCu\u00e1ndo entr\u00f3 en vigor el WLTP?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/swipcar.com\/es\/blog\/wltp\/#las-ventajas-y-desventajas-del-wltp\" >Las ventajas y desventajas del WLTP<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/swipcar.com\/es\/blog\/wltp\/#ventajas\" >Ventajas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/swipcar.com\/es\/blog\/wltp\/#desventajas\" >Desventajas<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<p>\u00bfNunca hab\u00edas o\u00eddo hablar del <strong>WLTP<\/strong>?, \u00a1no hay problema! En <a href=\"https:\/\/swipcar.com\/es\/renting-particulares\">Swipcar<\/a> nos gusta que nuestros conductores est\u00e9n siempre bien informados, y por eso hoy creamos este peque\u00f1o art\u00edculo de divulgaci\u00f3n (sin llegar a niveles demasiado t\u00e9cnicos). Sigue leyendo para salir de dudas de una vez por todas.<\/p>\n\n\n\n<!--more-->\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-theme-primary-background-color has-background\" href=\"https:\/\/swipcar.com\/es\/renting-particulares\" style=\"border-radius:50px\"><strong>Renting para particulares<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%c2%bfque-significa-wltp\"><\/span>\u00bfQu\u00e9 significa <em>WLTP<\/em>?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><strong>WLTP<\/strong> son las siglas simplificadas de <em>World Harmonized Light-duty Vehicle Test Procedure<\/em>, y es un <strong>est\u00e1ndar global con protocolos de pruebas para que un fabricante determine los niveles de contaminaci\u00f3n, emisiones de CO\u2082 y consumo de combustible de cualquier tipo de coche <\/strong>(tradicional, <a href=\"https:\/\/swipcar.com\/es\/blog\/coches-hibridos-ventajas-inconvenientes\" data-type=\"post\" data-id=\"9460\">h\u00edbrido<\/a> o <a href=\"https:\/\/swipcar.com\/es\/blog\/renting-coche-electrico\" data-type=\"post\" data-id=\"9393\">el\u00e9ctrico<\/a>). En el momento de publicaci\u00f3n de este art\u00edculo (finales de 2021) es el que tenemos en vigor en <strong>Espa\u00f1a<\/strong>.<\/p>\n\n\n\n<p>A grandes rasgos, debes saber que con este procedimiento tenemos una forma estandarizada m\u00e1s realista de comprobar y fijar los requisitos de contaminaci\u00f3n de los coches que se fabrican. Se prev\u00e9 que para 2030 esto consiga <strong>reducir la media de emisiones en un 30% <\/strong>con respecto a<strong> 2021.<\/strong><\/p>\n\n\n\n<p>Actualmente, la medida m\u00e1xima de emisi\u00f3n que define el WLTP es de<strong> 95\u202fg CO\u2082\/km<\/strong>, aunque esto es algo sujeto a posibles cambios.<\/p>\n\n\n\n<p>Antes de que se aplicase este protocolo para fabricantes hubo otro algo menos restrictivo (y m\u00e1s te\u00f3rico), conocido como <strong>NEDC<\/strong> (New European Driving Cycle), con unas emisiones m\u00e1ximas de <strong>168 g\/km de CO\u2082 <\/strong>en 2018, casi el doble de contaminante que el WLTP. Como veremos a continuaci\u00f3n, el cambio de NEDC a WLTP tiene algunos matices e implicaciones.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/swipcar.com\/wp-content\/uploads\/2021\/10\/nedcwltp-1024x576.jpeg\" alt=\"wltp\" class=\"wp-image-18570\" title=\"\" srcset=\"https:\/\/swipcar.com\/wp-content\/uploads\/2021\/10\/nedcwltp-1024x576.jpeg 1024w, https:\/\/swipcar.com\/wp-content\/uploads\/2021\/10\/nedcwltp-300x169.jpeg 300w, https:\/\/swipcar.com\/wp-content\/uploads\/2021\/10\/nedcwltp-768x432.jpeg 768w, https:\/\/swipcar.com\/wp-content\/uploads\/2021\/10\/nedcwltp-1536x864.jpeg 1536w, https:\/\/swipcar.com\/wp-content\/uploads\/2021\/10\/nedcwltp-600x338.jpeg 600w, https:\/\/swipcar.com\/wp-content\/uploads\/2021\/10\/nedcwltp.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%c2%bfcuando-entro-en-vigor-el-wltp\"><\/span>\u00bfCu\u00e1ndo entr\u00f3 en vigor el WLTP?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><strong>El WLTP entr\u00f3 en vigor de forma oficial el<\/strong> <strong>1 de septiembre de 2018<\/strong>, aunque en 2015 ya se hab\u00eda presentado p\u00fablicamente con el fin de que los fabricantes tuvieran margen para adaptar sus procesos de fabricaci\u00f3n a este protocolo.<\/p>\n\n\n\n<p>No obstante, y de ah\u00ed la importancia de que divulguemos informaci\u00f3n sobre este tema, es que <strong>hasta principios de 2021 no se ha implementado del todo en Espa\u00f1a. <\/strong>Esto es debido a que, en su momento, el Ministerio de Industria, Comercio y Turismo aprob\u00f3 una moratoria conforme la cual se podr\u00eda seguir usando coches fabricados con el protocolo NEDC hasta tal fecha.<\/p>\n\n\n\n<p>Como consecuencia, los fabricantes han tenido tiempo para adaptarse y vender r\u00e1pidamente (posiblemente a un precio reducido) todos los modelos que cumpl\u00edan con los requisitos m\u00ednimos del NEDC.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-theme-primary-background-color has-background\" href=\"https:\/\/swipcar.com\/es\/renting?fuel=hybrid\" style=\"border-radius:50px\"><strong>Coches el\u00e9ctricos en renting<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/swipcar.com\/wp-content\/uploads\/2021\/10\/coche-medido.jpeg\" alt=\"consumo wltp\" class=\"wp-image-18574\" title=\"\" srcset=\"https:\/\/swipcar.com\/wp-content\/uploads\/2021\/10\/coche-medido.jpeg 800w, https:\/\/swipcar.com\/wp-content\/uploads\/2021\/10\/coche-medido-300x169.jpeg 300w, https:\/\/swipcar.com\/wp-content\/uploads\/2021\/10\/coche-medido-768x432.jpeg 768w, https:\/\/swipcar.com\/wp-content\/uploads\/2021\/10\/coche-medido-600x338.jpeg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"las-ventajas-y-desventajas-del-wltp\"><\/span>Las ventajas y desventajas del WLTP<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>El nuevo protocolo de pruebas en laboratorios para comprobar que un coche cumple con todos los criterios anticontaminaciones, no solamente sirve para seleccionar<strong> coches m\u00e1s ecol\u00f3gicos<\/strong>. Aqu\u00ed van algunas de sus ventajas y desventajas:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"ventajas\"><\/span>Ventajas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>El protocolo WLTP permite medir la contaminaci\u00f3n bas\u00e1ndose en <strong>datos de conducci\u00f3n reales<\/strong>, a diferencia del NEDC que se basaba tan solo en la teor\u00eda.<\/li><li>Refleja mejor el <strong>consumo en carretera<\/strong>, de forma que los consumidores tendremos informaci\u00f3n m\u00e1s precisa sobre lo que esperamos gastar con cada coche.<\/li><li>Mejores condiciones de ensayo para evaluar el modelo antes de venderlo:<ul><li>Se tienen en cuenta los equipamientos opcionales en cada ensayo.<\/li><\/ul><ul><li>M\u00e1s situaciones de conducci\u00f3n evaluadas (urbanas, suburbanas, carretera y autopista).<\/li><li>Temperatura ambiente m\u00e1s realista (cercana a la europea).<\/li><li>Paradas m\u00e1s cortas.<\/li><li>Condiciones din\u00e1micas m\u00e1s representativas (cambios de marcha).<\/li><\/ul><\/li><li>Al ense\u00f1ar los datos sobre el autom\u00f3vil al consumidor no se utilizar\u00e1n datos <em>medios<\/em> como hasta ahora, sino que se muestran los resultados m\u00e1s negativos y positivos del veh\u00edculo en estas pruebas, con el fin de que el usuario tenga datos m\u00e1s realistas y tome mejores decisiones.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"desventajas\"><\/span>Desventajas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Condiciones m\u00e1s estrictas de configuraci\u00f3n y medici\u00f3n del coche, lo que ha hecho que algunos coches tengan que reducir su potencia u otras caracter\u00edsticas.<\/li><li>Distancias de prueba m\u00e1s largas, lo que alarga y encarece los procesos de prueba.<\/li><li>En algunos nichos, como en el caso de los SUV, <strong>encarece los precios de los coches en hasta un 5%.<\/strong><\/li><li>Debido a unas pruebas m\u00e1s realistas y precisamente a las restricciones, muchos coches dejan de poder venderse.<\/li><\/ul>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-theme-primary-background-color has-background\" href=\"https:\/\/swipcar.com\/es\/renting\" style=\"border-radius:50px\"><strong>renting de coches<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p>Puede parecerte que el nuevo protocolo <strong>WLTP <\/strong>tiene muchas desventajas para ti como comprador, que no deseas pagar m\u00e1s por lo mismo. No obstante, piensa que siempre puedes optar por el <a href=\"https:\/\/swipcar.com\/es\/renting\">renting<\/a>. Como te dijimos no hace mucho, \u00a1ten en cuenta que los <strong>precios del renting<\/strong> son mucho m\u00e1s econ\u00f3micos que la compra!, y por supuesto es un tipo de consumo m\u00e1s ecol\u00f3gico a largo plazo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfNunca hab\u00edas o\u00eddo hablar del WLTP?, \u00a1no hay problema! En Swipcar nos gusta que nuestros conductores est\u00e9n siempre bien informados, y por eso hoy creamos este peque\u00f1o art\u00edculo de divulgaci\u00f3n (sin llegar a niveles demasiado t\u00e9cnicos). Sigue leyendo para salir de dudas de una vez por todas.<\/p>\n","protected":false},"author":2966,"featured_media":18566,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[101],"tags":[7053],"class_list":{"0":"post-18565","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-movilidad-sostenible","8":"tag-wltp","9":"entry"},"priority_companies":"","priority_employees":"","priority_freelance":"","priority_home":"","_links":{"self":[{"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/posts\/18565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/users\/2966"}],"replies":[{"embeddable":true,"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/comments?post=18565"}],"version-history":[{"count":0,"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/posts\/18565\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/media\/18566"}],"wp:attachment":[{"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/media?parent=18565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/categories?post=18565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/tags?post=18565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}