{"id":13073,"date":"2021-05-06T11:19:00","date_gmt":"2021-05-06T09:19:00","guid":{"rendered":"https:\/\/swipcar.wpengine.com\/?p=13073"},"modified":"2025-09-23T13:33:07","modified_gmt":"2025-09-23T11:33:07","slug":"coche-aptera","status":"publish","type":"post","link":"https:\/\/swipcar.com\/es\/blog\/coche-aptera","title":{"rendered":"El nuevo coche Aptera \u00bfes el futuro de la conducci\u00f3n?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00bfEs posible superar en autonom\u00eda a los mejores <a href=\"https:\/\/swipcar.com\/es\/blog\/mejores-coches-electricos-2020\">coches el\u00e9ctricos<\/a> de la actualidad? Por supuesto que s\u00ed. <\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed ha quedado demostrado con la pr\u00f3xima salida de los&nbsp;<strong>coches aptera<\/strong>, unos autom\u00f3viles que superan con creces todas las expectativas habidas y por haber en la parte m\u00e1s ecol\u00f3gica del sector. Te lo contamos todo en&nbsp;<a href=\"https:\/\/swipcar.com\/es\">Swipcar<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Aptera, el coche el\u00e9ctrico que no se carga<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Con la evoluci\u00f3n de las iniciativas tecnol\u00f3gicas es normal que surjan nuevos modelos como el Aptera, cuyo significado es&nbsp;<em>objeto volador sin alas<\/em>. Este es un&nbsp;<strong>coche solar el\u00e9ctrico<\/strong>, con ni m\u00e1s ni menos que&nbsp;<strong>1.600 km de autonom\u00eda en una sola carga<\/strong>&nbsp;(en su versi\u00f3n de 100 kWh), pudi\u00e9ndose recargar con la energ\u00eda del sol en hasta 100 km diarios.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>El objetivo de\u00a0Aptera Motors\u00a0es crear el autom\u00f3vil m\u00e1s eficiente posible<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">En el siguiente video puedes ver algunas im\u00e1genes con el coche en acci\u00f3n:&nbsp;<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:1280px;max-width:100%;margin:5px;\"><div class=\"lyMe hidef\" id=\"WYL_HNjUdTJjiNk\"><div id=\"lyte_HNjUdTJjiNk\" data-src=\"https:\/\/swipcar.com\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FHNjUdTJjiNk%2Fmaxresdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/HNjUdTJjiNk\" rel=\"nofollow noopener\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/swipcar.com\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FHNjUdTJjiNk%2F0.jpg\" alt=\"YouTube video thumbnail\" width=\"1280\" height=\"700\" title=\"\"><br \/>Ver este v\u00eddeo en YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:1280px;margin:5px;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">No es de extra\u00f1ar que este coche, que parece sacado de alguna pel\u00edcula de superh\u00e9roes o una&nbsp;<em>nave espacial con ruedas<\/em>, haya sido un&nbsp;<strong>\u00e9xito total<\/strong>. Estamos hablando de&nbsp;<strong>m\u00e1s de 7.000 reservas<\/strong>&nbsp;hasta la fecha del \u00faltimo&nbsp;<strong>Aptera 2<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La reserva cuesta unos 100&nbsp;$, pero el&nbsp;<strong>precio del Aptera<\/strong>&nbsp;est\u00e1&nbsp;<strong>entre 21.340 \u20ac y 36.990 \u20ac<\/strong>, seg\u00fan la versi\u00f3n que escojas. Aqu\u00ed van las principales seg\u00fan la capacidad de bater\u00eda:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>100 kWh de capacidad, con 1.600 km de autonom\u00eda<\/li><li>60 kWh, con 965 km<\/li><li>40 kWh, con 643 km<\/li><li>25 kWh, con 402 km<\/li><\/ul>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>A\u00fan en su versi\u00f3n m\u00e1s ligera, es un coche que sigue sorprendiendo por su gran autonom\u00eda.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n hay versiones de tracci\u00f3n delantera o integral, para los que necesitan menor o mayor aceleraci\u00f3n, respectivamente.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-theme-primary-background-color has-background\" href=\"https:\/\/swipcar.com\/es\/renting?fuel=hybrid\" style=\"border-radius:50px\"><strong>ofertas de coches ecol\u00f3gicos en renting<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En su&nbsp;<strong>dise\u00f1o<\/strong>&nbsp;han pensado en todo, y es que su forma de gota de agua le proporciona la aerodin\u00e1mica que le hac\u00eda falta para&nbsp;<strong>reducir la resistencia del aire<\/strong>. Dado que siguen los principios de la aeron\u00e1utica para conseguirlo, es normal que el coche recuerde a los modelos de aviaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esta manera, el motor gasta mucha menos energ\u00eda para moverse, de hecho hasta&nbsp;<strong>dos y veces y media menos<\/strong>&nbsp;que los modelos el\u00e9ctricos. Finalmente, obtenemos un coche&nbsp;<strong>que gasta poco y corre durante muchos kil\u00f3metros<\/strong>, y que encima es auto-recargable.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"960\" height=\"541\" src=\"https:\/\/swipcar.com\/wp-content\/uploads\/2021\/05\/Aptera-coche-solar.jpeg\" alt=\"coche aptera\" class=\"wp-image-13076\" title=\"\" srcset=\"https:\/\/swipcar.com\/wp-content\/uploads\/2021\/05\/Aptera-coche-solar.jpeg 960w, https:\/\/swipcar.com\/wp-content\/uploads\/2021\/05\/Aptera-coche-solar-300x169.jpeg 300w, https:\/\/swipcar.com\/wp-content\/uploads\/2021\/05\/Aptera-coche-solar-768x433.jpeg 768w, https:\/\/swipcar.com\/wp-content\/uploads\/2021\/05\/Aptera-coche-solar-600x338.jpeg 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">El futuro de la conducci\u00f3n con coches solares<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hay que tener en cuenta que el prototipo de Aptera en realidad no es un coche al 100%, ya que hay que fijarse en sus&nbsp;<strong>tres ruedas<\/strong>, lo que lo convierte en un h\u00edbrido entre autom\u00f3vil y motocicleta.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dado que en Espa\u00f1a superar\u00eda la anchura m\u00e1xima para un veh\u00edculo de tres ruedas, de momento&nbsp;<strong>no estar\u00eda homologado para su circulaci\u00f3n<\/strong>, algo con lo que la empresa tendr\u00e1 que luchar o buscar la manera de superar en alg\u00fan momento.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si nos seguimos fijando en sus defectos, cabr\u00eda resaltar que solo tiene&nbsp;<strong>2 plazas<\/strong>&nbsp;(conductor, pasajero y una mascota). Esto es algo que podr\u00eda cambiar en modelos posteriores, ya que el&nbsp;<strong>maletero cuenta con hasta 700 litros<\/strong>&nbsp;de capacidad, lo que nos da una pista de que hay suficiente margen para a\u00f1adir m\u00e1s plazas.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-theme-primary-background-color has-background\" href=\"https:\/\/swipcar.com\/es\/renting?fuel=hybrid\" style=\"border-radius:50px\"><strong>VER coches ecol\u00f3gicos<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, el&nbsp;<strong>a\u00f1adido de las placas solares<\/strong>&nbsp;a un coche ya de por s\u00ed sorprendente, no hace m\u00e1s que subrayar un modelo&nbsp;<strong>brillante y revolucionario<\/strong>. Las placas se colocan, por supuesto, en la parte exterior del coche ya sea parcialmente o en toda la superficie (aprovechando, por ejemplo, la longitud de su maletero alargado).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dejando este coche aparcado bajo el sol en un d\u00eda de verano, seg\u00fan la empresa puedes llegar a&nbsp;<strong>recargar entre 60 y 100 km diarios<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin duda, estamos hablando de toda una&nbsp;<strong>revoluci\u00f3n en la conducci\u00f3n<\/strong>, que podr\u00eda estar m\u00e1s cerca de lo que creemos de la autosuficiencia energ\u00e9tica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El&nbsp;<strong>coche Aptera<\/strong>, que seg\u00fan sus fabricantes llegar\u00e1 al mercado en 2022, es solo una novedad del mundo automotriz que nos espera. Si quieres seguir informado no te olvides de <strong>suscribirte a nuestra lista de correo<\/strong> para mantenerte al d\u00eda sobre todas las noticias que te iremos dando. Por supuesto, mientras tanto podr\u00e1s seguir disfrutando de lo mejor en&nbsp;<a href=\"https:\/\/swipcar.com\/es\/renting-particulares\">renting para particulares<\/a>, tanto de coches el\u00e9ctricos como h\u00edbridos.<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>\u00bfEs posible superar en autonom\u00eda a los mejores coches el\u00e9ctricos de la actualidad? Por supuesto que s\u00ed.<\/p>\n","protected":false},"author":2966,"featured_media":13091,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[101],"tags":[6746,6745,6747,2115],"class_list":["post-13073","post","type-post","status-publish","format-standard","has-post-thumbnail","category-movilidad-sostenible","tag-aptera","tag-coche-solar","tag-placas-solares","tag-sostenibilidad","entry"],"priority_companies":"","priority_employees":"","priority_freelance":"","priority_home":"","_links":{"self":[{"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/posts\/13073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/users\/2966"}],"replies":[{"embeddable":true,"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/comments?post=13073"}],"version-history":[{"count":0,"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/posts\/13073\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/media\/13091"}],"wp:attachment":[{"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/media?parent=13073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/categories?post=13073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swipcar.com\/es\/wp-json\/wp\/v2\/tags?post=13073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}